{"id":330937,"date":"2025-10-24T22:07:23","date_gmt":"2025-10-24T20:07:23","guid":{"rendered":"https:\/\/dhagpo.org\/?p=330937"},"modified":"2025-10-24T22:55:35","modified_gmt":"2025-10-24T20:55:35","slug":"tschenresi-zyklus-8-jahr-reinen-sichtweise-ueben","status":"publish","type":"post","link":"https:\/\/dhagpo.org\/de\/tschenresi-zyklus-8-jahr-reinen-sichtweise-ueben\/","title":{"rendered":"Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||10px|||&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.21.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text admin_label=&#8220;Intro&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span style=\"font-weight: 400;\">Die reine Sichtweise und der Prozess, der zu einer Ver\u00e4nderung unserer gewohnten Sichtweise f\u00fchrt, standen im Mittelpunkt der Unterweisungen von Lama Jigme Rinpoche w\u00e4hrend des Tschenresi-Studien- und Meditationskurses, der vom 15. bis 19. Oktober 2025 in Dhagpo Kagyu Ling stattfand.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Da unsere Sichtweise durch leidvolle Verdunkelungen und unsere samsarischen Tendenzen getr\u00fcbt ist, orientiert sich unser Geist in eine Richtung, die uns daran hindert, mit unserer wahren Natur \u2013 unserem Weisheitspotenzial, unserer Buddha-Natur \u2013 in Kontakt zu bleiben. Das Erlernen des Dharma bietet Anhaltspunkte, um diese Funktionsweise zu verstehen. Es liegt dann an jedem\/jeder einzelnen, \u201edie Arbeit zu tun\u201d, um die Ereignisse, die im Geiste auftauchen, zu erkennen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Jigme Rinpoche, <a href=\"https:\/\/dhagpo.org\/de\/4-oktober-2018-beginn-tschenresi-curriculum-jigme-rinpoche-und-studierenden-instituts\/\">der diesen Zyklus seit Oktober 2018<\/a> mit drei Kursen pro Jahr leitet, erinnerte die Praktizierenden an das Ziel der Tschenresi-Praxis: sich von Leiden und Unwissenheit zu befreien und den Wesen hilfreich zu sein. Wenn uns die Tschenresi-Praxis erm\u00f6glicht, die Qualit\u00e4ten der Bodhisattvas zu offenbaren, m\u00fcssen wir dennoch wissen, wie wir in unserer Buddha-Natur verweilen k\u00f6nnen. Dazu m\u00fcssen wir das grundlegende Bewusstsein von allem klar verstehen \u2013 wie sich das gew\u00f6hnliche Bewusstsein des verwirrten Geistes und das urspr\u00fcngliche Bewusstsein in seinem Aspekt der Weisheit des erwachten Geistes entfalten. Der ganze Sinn der Meditation, erkl\u00e4rt Rinpoche, besteht darin, die Natur unseres Geistes zu verwirklichen. Ohne eine solide Meditationspraxis k\u00f6nnen wir die Tschenrezi-Praxis nicht richtig ausf\u00fchren. Wir m\u00fcssen also den Boden bereiten, damit sich eine Ver\u00e4nderung in der Ausrichtung unseres Geistes vollziehen kann, um zum Zustand eines Buddhas zu gelangen: indem wir unser Bodhichitta verbessern, das den Geist auf andere ausrichtet; indem wir die vorbereitenden \u00dcbungen durchf\u00fchren und die Bedeutung der Worte verstehen.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Jigme Rinpoche verwendete insbesondere das Sieben-Zweige-Gebet aus der Tschenresi-Praxis als Beispiel: <\/span><\/p>\n<blockquote>\n<p><em><span style=\"font-weight: 400;\">Das Nachdenken \u00fcber die Bedeutung jedes einzelnen Wortes gew\u00f6hnt den Geist daran, eine Richtung einzuschlagen, die durch Kraft und Unterscheidungsverm\u00f6gen nat\u00fcrlich zu einer reinen und gleichm\u00fctigen Sichtweise f\u00fchrt. Jede Alltagssituation ist eine Gelegenheit zum \u00dcben, so wie die Bodhisattvas jede Situation als Weg zur Erleuchtung nutzen. Durch die Vereinigung von Studium, Meditation und Tschenresi-Praxis wird unser Geist allm\u00e4hlich und auf nat\u00fcrliche Weise eine andere Sichtweise und Betrachtungsweise unserer Umgebung, anderer Menschen und von uns selbst annehmen. Die reine Sichtweise ist keineswegs ein Konzept, das k\u00fcnstlich entwickelt oder geschaffen werden muss, sondern geht Hand in Hand mit dem Verweilen in unserer Buddha-Natur. Der Weg ist schrittweise und st\u00fctzt sich auf die Lehren Buddhas.<\/span><\/em><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\"><strong>Jeden Nachmittag<\/strong> setzten die Studenten des Instituts die Wiederholung von Kapitel 2 des Abhidharmakosha \u00fcber die F\u00e4higkeiten fort. Von morgens bis abends war der Tag auch von verschiedenen Meditationen gepr\u00e4gt.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Im Rahmen des <strong>50-j\u00e4hrigen Jubil\u00e4ums von Dhagpo Kagyu Ling<\/strong> konnten die Praktizierenden des Kurses und aus der Umgebung auch einen besonderen Abend mit Trinley Rinpoche genie\u00dfen, an dem er <a href=\"https:\/\/dhagpo.org\/de\/oktober-2010-karmapa-erhaelt-uebertragung-schatzsammlung-kostbaren-unterweisungen-pewar-rinpoche\/\">\u00fcber seinen Weg im Dharma seit seiner Kindheit,<\/a> seine Erinnerungen an den 16. Gyalwa Karmapa und die Bedeutung der zahlreichen Dharma-\u00dcbertragungen sprach, die Thaye Dorje, Seine Heiligkeit, der 17. Gyalwa Karmapa, erhalten hat und bei denen er anwesend war. Diese \u00dcbertragungen sind seit der Zeit Buddhas ununterbrochen und vermitteln sowohl Wissen als auch Verwirklichung.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8220;nextgen&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#f7f7f7&#8243; custom_margin=&#8220;0px||||false|false&#8220; custom_padding=&#8220;15px|25px|25px|25px|false|false&#8220; hover_enabled=&#8220;0&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\nngg_shortcode_0_placeholder\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die reine Sichtweise und der Prozess, der zu einer Ver\u00e4nderung unserer gewohnten Sichtweise f\u00fchrt, standen im Mittelpunkt der Unterweisungen von Lama Jigme Rinpoche w\u00e4hrend des Tschenresi-Studien- und Meditationskurses, der vom [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":330968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>[et_pb_section fb_built=\"1\" _builder_version=\"4.21.0\" _module_preset=\"default\" custom_padding=\"||10px|||\" locked=\"off\" global_colors_info=\"{}\"][et_pb_row _builder_version=\"4.21.0\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column type=\"4_4\" _builder_version=\"4.21.0\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text admin_label=\"Intro\" _builder_version=\"4.27.4\" _module_preset=\"default\" global_colors_info=\"{}\"]<\/p><p>La vision pure et le processus pour qu\u2019un changement s\u2019op\u00e8re au niveau de notre fa\u00e7on habituelle d\u2019envisager les choses \u00e9taient au c\u0153ur de l\u2019enseignement donn\u00e9 par lama Jigm\u00e9 Rinpoch\u00e9 lors du cursus d\u2019\u00e9tude et de m\u00e9ditation du cycle Chenrezik, qui s\u2019est tenu \u00e0 Dhagpo Kagyu Ling du 15 au 19 octobre 2025.<\/p><p>Parce que notre vision est color\u00e9e par les obscurcissements affligeants, par nos tendances samsariques, notre esprit s\u2019oriente dans une direction qui nous emp\u00eache de rester au contact de notre v\u00e9ritable nature \u2013 notre potentiel de sagesse, notre nature de bouddha. L\u2019apprentissage du Dharma offre des r\u00e9f\u00e9rences qui permettent de comprendre ce fonctionnement\u00a0; il appartient ensuite \u00e0 chacun de \u00ab\u00a0faire le travail\u00a0\u00bb pour identifier les \u00e9v\u00e9nements de l\u2019esprit qui s\u2019\u00e9l\u00e8vent.<\/p><p>Jigm\u00e9 Rinpoch\u00e9, qui<a href=\"https:\/\/dhagpo.org\/4-octobre-2018-debut-cursus-chenrezik-lama-jigme-rinpoche-etudiants-institut\/\"> guide ce cursus \u00e0 raison de trois stages par an depuis octobre 2018<\/a>, a rappel\u00e9 aux pratiquants<strong> le but de la pratique de Chenrezik<\/strong>\u00a0: se lib\u00e9rer du mal-\u00eatre et de l\u2019ignorance, et \u00eatre utile aux \u00eatres. Si la pratique de Chenrezik nous permet de r\u00e9v\u00e9ler les qualit\u00e9s des bodhisattvas, encore faut-il savoir demeurer en notre nature de bouddha. Pour cela, il nous faut d\u2019une part comprendre clairement la conscience base de tout \u2013 base pour le d\u00e9ploiement de la conscience ordinaire qui est l\u2019aspect confus de l\u2019esprit \u2013 , d\u2019autre part comprendre clairement la conscience primordiale qui est l\u2019aspect de sagesse de l\u2019esprit \u00e9veill\u00e9. Tout le propos de la m\u00e9ditation, explique Rinpoch\u00e9, est l\u00e0\u00a0: r\u00e9aliser la nature de notre esprit. Sans une solide pratique de la m\u00e9ditation, nous ne pouvons pas accomplir la pratique de Chenrezik correctement.<\/p><p>Il nous faut donc pr\u00e9parer le terrain pour qu\u2019un changement puisse s\u2019op\u00e9rer quant \u00e0 l\u2019orientation de notre esprit afin de progresser vers l\u2019\u00e9tat de bouddha\u00a0: en am\u00e9liorant notre <em>bodhichitta<\/em>\u00a0qui tourne l\u2019esprit vers les autres\u00a0; en accomplissant les pratiques pr\u00e9liminaires et en comprenant le sens des mots. Jigm\u00e9 Rinpoch\u00e9 a notamment utilis\u00e9 comme exemple la pri\u00e8re \u00e0 sept branches incluse dans la pratique de Chenrezik\u00a0:<\/p><blockquote><p><em>r\u00e9fl\u00e9chir au sens de chaque mot habitue l\u2019esprit \u00e0 s\u2019entra\u00eener au discernement qui lui permettra d\u2019adopter naturellement une vision pure et \u00e9quanime. Toute situation du quotidien est une opportunit\u00e9 pour s\u2019entrainer, \u00e0 l\u2019instar des bodhisattvas qui utilisent toute situation comme voie vers l\u2019\u00e9veil. Par l\u2019union de l\u2019\u00e9tude, de la m\u00e9ditation et de la pratique de Chenrezik, notre esprit va progressivement et naturellement embrasser une autre fa\u00e7on de voir et d\u2019envisager notre environnement, les autres et nous-m\u00eames. <\/em><\/p><p><em>La vision pure n\u2019est en aucun cas un concept. Elle ne s\u2019\u00e9labore ni ne se cr\u00e9e artificiellement, mais elle va de pair avec le fait de demeurer dans la nature de bouddha. Le cheminement est progressif et s\u2019appuie sur la r\u00e9f\u00e9rence des enseignements du Bouddha.<\/em><\/p><\/blockquote><p>Chaque apr\u00e8s-midi, les \u00e9tudiants de l\u2019Institut <strong>ont continu\u00e9 la restitution<\/strong> du chapitre 2 de l\u2019<em>Abhidharmakosha<\/em> portant sur les facult\u00e9s. Du matin au soir, la journ\u00e9e \u00e9tait aussi rythm\u00e9e par diff\u00e9rentes pratiques m\u00e9ditatives.<\/p><p>Dans le cadre des <a href=\"https:\/\/dhagpo.org\/bouddhisme\/50-ans\/\">50 ans de Dhagpo Kagyu Ling,<\/a> les pratiquants du cursus et des alentours ont aussi pu b\u00e9n\u00e9ficier d\u2019une soir\u00e9e sp\u00e9ciale avec Thinlay Rinpoch\u00e9. Il a \u00e9voqu\u00e9 son cheminement dans le Dharma depuis l\u2019enfance, ses souvenirs du XVI<sup>\u1d49<\/sup> Gyalwa Karmapa et<a href=\"https:\/\/dhagpo.org\/octobre-2010-karmapa-recoit-pewar-rinpoche-transmission-tresor-instructions-precieuses\/\"> le sens des nombreuses transmissions du Dharma<\/a> re\u00e7ues par Thay\u00e9 Dorj\u00e9, Sa Saintet\u00e9 le XVII\u1d49\u00a0Gyalwa Karmapa \u2013 transmissions pour lesquelles il \u00e9tait \u00e9galement pr\u00e9sent. Ces transmissions sont ininterrompues depuis le temps du Bouddha, et elles v\u00e9hiculent \u00e0 la fois la connaissance et la r\u00e9alisation.<\/p><p>[\/et_pb_text][et_pb_text admin_label=\"nextgen\" _builder_version=\"4.27.4\" _module_preset=\"default\" background_color=\"#d4b16a\" custom_margin=\"0px||||false|false\" custom_padding=\"15px|25px|25px|25px|false|false\" locked=\"off\" global_colors_info=\"{}\"]<\/p>[ngg src=\"galleries\" ids=\"61\" display=\"pro_mosaic\" order_by=\"filename\"]<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>","_et_gb_content_width":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[117,120],"tags":[],"class_list":["post-330937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dhagpo-kagyu-ling-de","category-lama-jigme-rinpoche-de","et-has-post-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben - Dhagpo Kagyu Ling<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben - Dhagpo Kagyu Ling\" \/>\n<meta property=\"og:description\" content=\"Die reine Sichtweise und der Prozess, der zu einer Ver\u00e4nderung unserer gewohnten Sichtweise f\u00fchrt, standen im Mittelpunkt der Unterweisungen von Lama Jigme Rinpoche w\u00e4hrend des Tschenresi-Studien- und Meditationskurses, der vom [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/\" \/>\n<meta property=\"og:site_name\" content=\"Dhagpo Kagyu Ling\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-24T20:07:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T20:55:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhagpo.org\/wp-content\/uploads\/2020\/10\/Cursus-chenrezik_octobre-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"yone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"yone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/\"},\"author\":{\"name\":\"yone\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/#\\\/schema\\\/person\\\/5599c0ac81613f26c092fd8eb9b35828\"},\"headline\":\"Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben\",\"datePublished\":\"2025-10-24T20:07:23+00:00\",\"dateModified\":\"2025-10-24T20:55:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/\"},\"wordCount\":654,\"image\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhagpo.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Cursus-chenrezik_octobre-2025.jpg\",\"articleSection\":[\"Dhagpo Kagyu Ling\",\"Lama Jigme Rinpoche\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/\",\"url\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/\",\"name\":\"Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben - Dhagpo Kagyu Ling\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhagpo.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Cursus-chenrezik_octobre-2025.jpg\",\"datePublished\":\"2025-10-24T20:07:23+00:00\",\"dateModified\":\"2025-10-24T20:55:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/#\\\/schema\\\/person\\\/5599c0ac81613f26c092fd8eb9b35828\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhagpo.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Cursus-chenrezik_octobre-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/dhagpo.org\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Cursus-chenrezik_octobre-2025.jpg\",\"width\":700,\"height\":526},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dhagpo.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dhagpo Kagyu Ling\",\"item\":\"https:\\\/\\\/dhagpo.org\\\/es\\\/categorie\\\/dhagpo-kagyu-ling\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/#website\",\"url\":\"https:\\\/\\\/dhagpo.org\\\/\",\"name\":\"Dhagpo Kagyu Ling\",\"description\":\"Un lieu pour comprendre et vivre le bouddhisme\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dhagpo.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/#\\\/schema\\\/person\\\/5599c0ac81613f26c092fd8eb9b35828\",\"name\":\"yone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g\",\"caption\":\"yone\"},\"url\":\"https:\\\/\\\/dhagpo.org\\\/de\\\/author\\\/yone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben - Dhagpo Kagyu Ling","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/","og_locale":"de_DE","og_type":"article","og_title":"Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben - Dhagpo Kagyu Ling","og_description":"Die reine Sichtweise und der Prozess, der zu einer Ver\u00e4nderung unserer gewohnten Sichtweise f\u00fchrt, standen im Mittelpunkt der Unterweisungen von Lama Jigme Rinpoche w\u00e4hrend des Tschenresi-Studien- und Meditationskurses, der vom [&hellip;]","og_url":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/","og_site_name":"Dhagpo Kagyu Ling","article_published_time":"2025-10-24T20:07:23+00:00","article_modified_time":"2025-10-24T20:55:35+00:00","og_image":[{"width":700,"height":526,"url":"https:\/\/dhagpo.org\/wp-content\/uploads\/2020\/10\/Cursus-chenrezik_octobre-2025.jpg","type":"image\/jpeg"}],"author":"yone","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"yone","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/#article","isPartOf":{"@id":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/"},"author":{"name":"yone","@id":"https:\/\/dhagpo.org\/#\/schema\/person\/5599c0ac81613f26c092fd8eb9b35828"},"headline":"Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben","datePublished":"2025-10-24T20:07:23+00:00","dateModified":"2025-10-24T20:55:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/"},"wordCount":654,"image":{"@id":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/#primaryimage"},"thumbnailUrl":"https:\/\/dhagpo.org\/wp-content\/uploads\/2020\/10\/Cursus-chenrezik_octobre-2025.jpg","articleSection":["Dhagpo Kagyu Ling","Lama Jigme Rinpoche"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/","url":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/","name":"Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben - Dhagpo Kagyu Ling","isPartOf":{"@id":"https:\/\/dhagpo.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/#primaryimage"},"image":{"@id":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/#primaryimage"},"thumbnailUrl":"https:\/\/dhagpo.org\/wp-content\/uploads\/2020\/10\/Cursus-chenrezik_octobre-2025.jpg","datePublished":"2025-10-24T20:07:23+00:00","dateModified":"2025-10-24T20:55:35+00:00","author":{"@id":"https:\/\/dhagpo.org\/#\/schema\/person\/5599c0ac81613f26c092fd8eb9b35828"},"breadcrumb":{"@id":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/#primaryimage","url":"https:\/\/dhagpo.org\/wp-content\/uploads\/2020\/10\/Cursus-chenrezik_octobre-2025.jpg","contentUrl":"https:\/\/dhagpo.org\/wp-content\/uploads\/2020\/10\/Cursus-chenrezik_octobre-2025.jpg","width":700,"height":526},{"@type":"BreadcrumbList","@id":"https:\/\/dhagpo.org\/cycle-chenrezik-annee-8-s-entrainer-vision-pure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dhagpo.org\/de\/"},{"@type":"ListItem","position":2,"name":"Dhagpo Kagyu Ling","item":"https:\/\/dhagpo.org\/es\/categorie\/dhagpo-kagyu-ling\/"},{"@type":"ListItem","position":3,"name":"Tschenresi-Zyklus 8. Jahr: Sich in der reinen Sichtweise \u00fcben"}]},{"@type":"WebSite","@id":"https:\/\/dhagpo.org\/#website","url":"https:\/\/dhagpo.org\/","name":"Dhagpo Kagyu Ling","description":"Un lieu pour comprendre et vivre le bouddhisme","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dhagpo.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/dhagpo.org\/#\/schema\/person\/5599c0ac81613f26c092fd8eb9b35828","name":"yone","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g","caption":"yone"},"url":"https:\/\/dhagpo.org\/de\/author\/yone\/"}]}},"_links":{"self":[{"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/posts\/330937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/comments?post=330937"}],"version-history":[{"count":6,"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/posts\/330937\/revisions"}],"predecessor-version":[{"id":330979,"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/posts\/330937\/revisions\/330979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/media\/330968"}],"wp:attachment":[{"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/media?parent=330937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/categories?post=330937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dhagpo.org\/de\/wp-json\/wp\/v2\/tags?post=330937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}