{"id":322925,"date":"2025-06-25T17:39:31","date_gmt":"2025-06-25T15:39:31","guid":{"rendered":"https:\/\/dhagpo.org\/?p=322925"},"modified":"2025-06-26T10:28:43","modified_gmt":"2025-06-26T08:28:43","slug":"31-julio-2015-consagracion-instituto-dhagpo-kagyu-ling","status":"publish","type":"post","link":"https:\/\/dhagpo.org\/es\/31-julio-2015-consagracion-instituto-dhagpo-kagyu-ling\/","title":{"rendered":"31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb _builder_version=\u00bb4.27.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_4&#8243; specialty_columns=\u00bb3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner _builder_version=\u00bb4.27.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_free_form=\u00bbimg.inline-zoom {||  transition: transform 0.3s ease;||  display: inline-block;||  vertical-align: middle;||  max-width: 100%;||}||||img.inline-zoom:hover {||  transform: scale(2);||  z-index: 10;||}\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">Dos a\u00f1os despu\u00e9s de <a href=\"https:\/\/dhagpo.org\/es\/13-junio-inauguracion-instituto-dhagpo-kagyu-ling\/\">su inauguraci\u00f3n por Kunzig Shamar Rimpoch\u00e9,<\/a> el Instituto Dhagpo Kagyu Ling fue <strong>formalmente consagrado<\/strong> y la estatua del Buda Shakyamuni fue desvelada por Thaye Dorje, Su Santidad el XVII Gyalwa Karmapa, el 31 de julio de 2015, \u00faltimo d\u00eda de su visita.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-322336  alignleft\" src=\"https:\/\/dhagpo.org\/wp-content\/uploads\/2000\/06\/31_karmapa-dhagpo-institut-31.jpg\" alt=\"\" width=\"327\" height=\"490\"><span style=\"font-weight: 400;\">Realizado por un maestro espiritual, el ritual de consagraci\u00f3n \u2014<\/span><i><span style=\"font-weight: 400;\">rabne<\/span><\/i><span style=\"font-weight: 400;\"> en tibetano\u2014 invita a los budas y bodhisattvas de las diez direcciones a habitar los objetos sagrados y lugares de culto, infundi\u00e9ndoles la esencia iluminada de su Cuerpo, Palabra y Mente. Este acto establece su <strong>presencia para que puedan beneficiar a todos los seres<\/strong> sintientes en su pr\u00e1ctica espiritual; tambi\u00e9n purifica el lugar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tras una hora de oraciones en el atrio del Instituto, el Gyalwa Karmapa, portando la cofia amarilla llamada de Gampopa, entr\u00f3 al interior para consagrar el lugar. <strong>El velo que cubr\u00eda el rostro de la estatua fue retirado<\/strong>, revelando su expresi\u00f3n radiante y serena.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Esta estatua<\/strong> del Buda, cuyas <strong>manos forman el <\/strong><\/span><strong><i>mudra<\/i><\/strong><span style=\"font-weight: 400;\"><strong> de la ense\u00f1anza,<\/strong> fue rellenada con rollos de mantras y sustancias preciosas colocadas la v\u00edspera de la consagraci\u00f3n por Ch\u00f6p\u00f6nla en el <\/span><i><span style=\"font-weight: 400;\">soching<\/span><\/i><span style=\"font-weight: 400;\">, el \u201c\u00e1rbol de la vida\u201d en su centro. Entre estas sustancias: una reliquia del anterior Buda Kashyapa donada por lama Jigme Rimpoch\u00e9 \u2014quien la hab\u00eda recibido del XVI Karmapa\u2014; una reliquia del Buda Shakyamuni ofrecida por <\/span><i><span style=\"font-weight: 400;\">khempo <\/span><\/i><span style=\"font-weight: 400;\">Chodrak Rimpoch\u00e9; a la altura del coraz\u00f3n, una peque\u00f1a estatua que proviene de Tsurpu (T\u00edbet), ofrecida por Jigme Rimpoch\u00e9; y, en bolsitas de tela, arroz bendecido por el XVI Karmapa, reliquias corporales del V Shamarpa, del VIII Shamarpa y del XVI Karmapa, p\u00edldoras de longevidad de varios Karmapas, p\u00edldoras elaboradas con tierra de numerosos lugares sagrados budistas, etc. As\u00ed, esta estatua del Buda, convertida en recept\u00e1culo del Cuerpo, Palabra y Mente del Buda, se transforma en un poderoso soporte de bendiciones para toda persona que entra en el Instituto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La estatua, hecha de l\u00e1minas de cobre recubiertas de oro, es obra de un artista franc\u00e9s, G\u00e9rard Guinot, quien tambi\u00e9n realiz\u00f3<a href=\"https:\/\/dhagpo.org\/es\/21-julio-2001-buda-gran-templo-kundreul-ling-creacion-consagracion\/\"> la gran estatua de Dhagpo Kundreul Ling,<\/a> las estupas del jard\u00edn de Sukhavati en Dhagpo Kagyu Ling y las de Karma Migyur Ling, as\u00ed como numerosas estatuas y estupas en Sharminub (Nepal), Rumtek (India), Estados Unidos, Alemania y Espa\u00f1a. Para la estatua del Instituto, recibi\u00f3 el encargo de Kunzig Shamar Rimpoch\u00e9, quien le dio como referencia la reproducci\u00f3n de una estatua de piedra de un per\u00edodo floreciente del arte budista.<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Le ped\u00ed que me diera consejos, pero me dijo: \u201c\u00a1T\u00fa sabes!\u201d No comprend\u00eda bien lo que significaba, pero con el tiempo me di cuenta de que lo m\u00e1s importante es captar profundamente el aspecto meditativo, entenderlo desde dentro. No se puede hacer algo si no se comprende. No se puede transmitir el sentido de algo si no se ha percibido. Es una pr\u00e1ctica que realmente nace desde el interior, explica G\u00e9rard.<\/span><\/p>\n<\/blockquote>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_free_form=\u00bbimg.inline-zoom {||  transition: transform 0.3s ease;||  display: inline-block;||  vertical-align: middle;||  max-width: 100%;||}||||img.inline-zoom:hover {||  transform: scale(2);||  z-index: 10;||}\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"font-weight: 400;\">Inspirado por el antiguo Egipto y el arte de las catedrales, G\u00e9rard descubri\u00f3 el budismo en el templo de Dashang Kagyu Ling en Borgo\u00f1a, donde conoci\u00f3 a Jamgon Kongtrul Rimpoch\u00e9 y Kalu Rimpoch\u00e9, y se form\u00f3 con escultores butaneses. \u00bfLa mano del artista representa un puente entre Oriente y Occidente, una expresi\u00f3n de b\u00fasqueda espiritual?&nbsp;<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">Yo, que comenc\u00e9 en Occidente sin referencias ni transmisi\u00f3n, me vi obligado a cuestionar todo eso. \u00bfQu\u00e9 se transmite? No todo est\u00e1 codificado. Uno tiene que tomar decisiones. Para m\u00ed, eso me oblig\u00f3 a intentar volver a la fuente, a lo esencial. Por eso las estatuas que hacemos aqu\u00ed son muy simples, sin muchos detalles.<\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\"><strong> A diferencia de la estatua de Kundreul Ling,<\/strong> el artista ensambl\u00f3 la estatua del Instituto en su taller de Borgo\u00f1a, para entregarla en una sola pieza a Dhagpo Kagyu Ling.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hicieron falta casi quince a\u00f1os para que se reunieran las causas y condiciones necesarias para que el proyecto del Instituto viera la luz. El 15 de agosto de 2002, la losa de lo que se convertir\u00eda en el Instituto fue consagrada por el Gyalwa Karmapa, junto al XIV Shamarpa, y se coloc\u00f3 la primera piedra. El proyecto se interrumpi\u00f3 a mitad de camino para ser revisado y adaptarlo mejor al lugar y a las necesidades. Se relanz\u00f3 en 2010 y fue finalizado sin obst\u00e1culos. Inaugurado y ahora consagrado, el edificio del Instituto permite hoy compartir la ense\u00f1anza del Buda de forma aut\u00e9ntica, aprender en comunidad y as\u00ed avanzar juntos hacia el despertar. La sabidur\u00eda que emana de la estatua del Buda en el Instituto es una<strong> invitaci\u00f3n a la contemplaci\u00f3n y una fuente de bendiciones<\/strong> para todas las personas que se encuentren en su presencia.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbnextgen \u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#d4b16a\u00bb custom_margin=\u00bb0px||||false|false\u00bb custom_padding=\u00bb|0px||0px|false|false\u00bb border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#ab0032&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\nngg_shortcode_0_placeholder\n<p>[\/et_pb_text][et_pb_text disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbRoboto||||||||\u00bb text_font_size=\u00bb13px\u00bb text_line_height=\u00bb1em\u00bb custom_padding=\u00bb||0px|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #808080;\">Estas fotos provienen de nuestros archivos o han sido recopiladas en el marco de la b\u00fasqueda para los 50 a\u00f1os de Dhagpo Kagyu Ling. No hemos podido identificar a todos los autores. El uso de las fotos es \u00fanicamente informativo y en el contexto de la celebraci\u00f3n de los 50 a\u00f1os de Dhagpo Kagyu Ling. Su uso est\u00e1 limitado a esta actividad y a nuestro sitio web, y no tiene fines comerciales.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text module_class=\u00bbevent50&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb||||||||\u00bb text_font_size=\u00bb16px\u00bb text_line_height=\u00bb20px\u00bb header_4_text_color=\u00bbgcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138&#8243; header_5_text_color=\u00bbgcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138&#8243; header_5_font_size=\u00bb18px\u00bb background_color=\u00bbgcid-b7d546b1-e8dd-4bef-9120-39ab5cda29e6&#8243; background_image=\u00bbhttps:\/\/dhagpo.org\/wp-content\/uploads\/2024\/12\/50ans-1.png\u00bb background_size=\u00bbcustom\u00bb background_image_width=\u00bb40px\u00bb background_position=\u00bbtop_right\u00bb background_horizontal_offset=\u00bb9px\u00bb background_vertical_offset=\u00bb6px\u00bb custom_margin=\u00bb||||false|false\u00bb custom_margin_tablet=\u00bb30px|100px|||false|false\u00bb custom_margin_phone=\u00bb|0px||0px|false|false\u00bb custom_margin_last_edited=\u00bboff|desktop\u00bb custom_padding=\u00bb|20px|15px|20px|false|false\u00bb custom_padding_tablet=\u00bb|20px|15px|20px|false|false\u00bb custom_padding_phone=\u00bb||||false|false\u00bb custom_padding_last_edited=\u00bbon|desktop\u00bb custom_css_main_element=\u00bbfont-weight:500;\u00bb custom_css_free_form=\u00bb.event50 h5 {||  display: inline-block;||  background-color: #ffffff; \/* Fond blanc *\/||  box-shadow: 0 2px 4px rgba(0, 0, 0, 0.1); \/* Optionnel : l\u00e9g\u00e8re ombre *\/||  padding: 5px; \/* Ajuster selon vos besoins *\/||  margin-bottom:10px;||  text-align: left; \/* Garde le texte align\u00e9 \u00e0 gauche *\/||||}||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-b7d546b1-e8dd-4bef-9120-39ab5cda29e6%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93,%22gcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138%22:%91%22header_4_text_color%22,%22header_5_text_color%22,%22header_4_text_color%22,%22header_5_text_color%22%93}\u00bb]<\/p>\n<h5>Evento<\/h5>\n<p>Para conmemorar este acontecimiento, recitaremos oraciones de aspiraci\u00f3n de los Kagyu Monlam de 11:00 a 12:30 h en el Templo.[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/dhagpo.org\/es\/calendrier\/50-anos-50-anos-31-julio-2015-consagracion-instituto-dhagpo-kagyu-ling\/\u00bb button_text=\u00bbVer en el calendario del programa\u00bb disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb button_text_color=\u00bbgcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_color=\u00bbgcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138&#8243; button_border_radius=\u00bb6px\u00bb button_icon=\u00bb&#xf073;||fa||400&#8243; button_icon_placement=\u00bbleft\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138%22:%91%22button_text_color%22,%22button_border_color%22,%22button_border_color__hover%22%93}\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_border_radius__hover=\u00bb6px\u00bb button_border_color__hover_enabled=\u00bbon|hover\u00bb button_border_color__hover=\u00bb#b87d06&#8243; button_bg_color__hover=\u00bb#FFFFFF\u00bb][\/et_pb_button][et_pb_text disabled_on=\u00bboff|off|on\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbRoboto||||||||\u00bb text_font_size=\u00bb13px\u00bb text_line_height=\u00bb1em\u00bb custom_padding=\u00bb||0px|||\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #808080;\">Estas fotos provienen de nuestros archivos o han sido recopiladas en el marco de la b\u00fasqueda para los 50 a\u00f1os de Dhagpo Kagyu Ling. No hemos podido identificar a todos los autores. El uso de las fotos es \u00fanicamente informativo y en el contexto de la celebraci\u00f3n de los 50 a\u00f1os de Dhagpo Kagyu Ling. Su uso est\u00e1 limitado a esta actividad y a nuestro sitio web, y no tiene fines comerciales.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos a\u00f1os despu\u00e9s de su inauguraci\u00f3n por Kunzig Shamar Rimpoch\u00e9, el Instituto Dhagpo Kagyu Ling fue formalmente consagrado y la estatua del Buda Shakyamuni fue desvelada por Thaye Dorje, Su [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"[et_pb_section fb_built=\"1\" specialty=\"on\" _builder_version=\"4.27.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column type=\"3_4\" specialty_columns=\"3\" _builder_version=\"4.16\" custom_padding=\"|||\" global_colors_info=\"{}\" custom_padding__hover=\"|||\"][et_pb_row_inner _builder_version=\"4.27.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_column_inner saved_specialty_column_type=\"3_4\" _builder_version=\"4.27.3\" _module_preset=\"default\" global_colors_info=\"{}\"][et_pb_text _builder_version=\"4.27.4\" _module_preset=\"default\" custom_css_free_form=\"img.inline-zoom {||  transition: transform 0.3s ease;||  display: inline-block;||  vertical-align: middle;||  max-width: 100%;||}||||img.inline-zoom:hover {||  transform: scale(2);||  z-index: 10;||}\" global_colors_info=\"{}\"]<p>Deux ans apr\u00e8s son<a href=\"https:\/\/dhagpo.org\/13-juin-2013-inauguration-institut-dhagpo-kagyu-ling\/\"> inauguration par K\u00fcnzik Shamar Rinpoch\u00e9,<\/a> <strong>l\u2019Institut<\/strong> de Dhagpo Kagyu Ling est formellement <strong>consacr\u00e9 et la statue du Bouddha Shakyamuni d\u00e9voil\u00e9e<\/strong> par Thay\u00e9 Dorj\u00e9, Sa Saintet\u00e9 le XVII<sup>e<\/sup> Gyalwa Karmapa, le 31 juillet 2015, dernier jour de sa visite.<\/p>\r\n<p><img class=\"wp-image-322336  alignleft\" src=\"https:\/\/dhagpo.org\/wp-content\/uploads\/2000\/06\/31_karmapa-dhagpo-institut-31.jpg\" alt=\"\" width=\"327\" height=\"490\" \/>Accompli par un ma\u00eetre spirituel, le rituel de cons\u00e9cration, ou <em>rabn\u00e9<\/em> en tib\u00e9tain, invite les bouddhas et les bodhisattvas des dix directions \u00e0 habiter les objets sacr\u00e9s et lieux de culte, en leur communiquant l\u2019essence \u00e9veill\u00e9e de leurs corps, parole et esprit. Cet acte \u00e9tablit leur pr\u00e9sence afin qu\u2019ils puissent \u00eatre <strong>b\u00e9n\u00e9fiques \u00e0 tous les \u00eatres sensibles<\/strong> dans leur pratique spirituelle ; il purifie \u00e9galement le lieu.<\/p>\r\n<p>Apr\u00e8s une heure de pri\u00e8res accomplies sur le parvis de l\u2019Institut, le Gyalwa Karmapa, portant la coiffe jaune dite de Gampopa, p\u00e9n\u00e8tre \u00e0 l\u2019int\u00e9rieur pour consacrer le lieu. <strong>Le voile recouvrant le visage de la statue est retir\u00e9<\/strong> pour r\u00e9v\u00e9ler son visage \u00e0 la fois rayonnant et recueilli.<\/p>\r\n<p>Cette <strong>statue<\/strong> du Bouddha, dont les <strong>mains forment le mudra de l\u2019enseignement<\/strong>, est remplie de rouleaux de mantras et de substances pr\u00e9cieuses plac\u00e9es la veille de la cons\u00e9cration par Ch\u00f6p\u00f6nla dans le <em>soching<\/em>, l\u2019arbre de vie en son centre. <strong>Parmi ces substances<\/strong> : une relique du pr\u00e9c\u00e9dent Bouddha Kashyapa donne\u0301e par lama Jigm\u00e9 Rinpoch\u00e9 qui l\u2019avait lui-m\u00eame re\u00e7ue du XVI<sup>e<\/sup> Karmapa ; une relique du Bouddha Shakyamuni offerte par <em>khenpo<\/em> Ch\u00f6drak Rinpoch\u00e9 ; au niveau du c\u0153ur, une petite statue provenant de Tsurpu au Tibet et offerte par Jigme\u0301 Rinpoche\u0301 ; et dans des sachets en tissu, du riz b\u00e9ni par le XVI<sup>e<\/sup> Karmapa, des reliques corporelles du V<sup>e<\/sup> Shamarpa, du VIII<sup>e<\/sup> Shamarpa et du XVI<sup>e<\/sup> Karmapa, des pilules de long\u00e9vit\u00e9 provenant de plusieurs Karmapas, des pilules faites de terre provenant de nombreux lieux saints bouddhistes, etc. Ainsi, cette statue de bouddha, devenue le r\u00e9ceptacle du corps, de la parole et de l\u2019esprit du Bouddha, est transform\u00e9e en un puissant support de b\u00e9n\u00e9diction pour toute personne entrant dans l\u2019Institut.<\/p>\r\n<p>La statue, constitu\u00e9e de feuilles de cuivre recouvertes d\u2019or, est l\u2019\u0153uvre d\u2019un artiste fran\u00e7ais, G\u00e9rard Guinot, qui a \u00e9galement r\u00e9alis\u00e9 <a href=\"https:\/\/dhagpo.org\/21-juillet-2001-bouddha-grand-temple-kundreul-ling-creation-consecration\/\">la grande statue de Dhagpo Kundreul Ling<\/a>, les stoupas du jardin de Sukhavati \u00e0 Dhagpo Kagyu Ling et ceux de Karma Migyur Ling, ainsi que de nombreuses statues et stoupas \u00e0 Sharminub au N\u00e9pal, \u00e0 Rumtek en Inde, aux \u00c9tats-Unis ou encore en Allemagne et en Espagne. Pour la statue de l\u2019Institut, il re\u00e7oit la commande de K\u00fcnzik Shamar Rinpoch\u00e9, qui lui donne comme r\u00e9f\u00e9rence la reproduction d\u2019une statue en pierre d\u2019une p\u00e9riode florissante de l\u2019art bouddhique.<\/p>\r\n<blockquote>\r\n<p>Je lui demandai de me donner des conseils, mais il m\u2019a dit \u201cvous savez !\u201d Je ne savais pas exactement ce que \u00e7a voulait dire, mais avec le temps, je m\u2019aper\u00e7ois que ce qui est le plus important, c\u2019est d\u2019avoir le sens profond de l\u2019aspect m\u00e9ditatif, de comprendre en profondeur, de l\u2019int\u00e9rieur. On ne peut pas faire quelque chose si on ne le comprend pas. On ne peut pas transmettre le sens de quelque chose si on ne l\u2019a pas aper\u00e7u. C\u2019est une pratique qui part vraiment de l\u2019int\u00e9rieur.<\/p>\r\n<\/blockquote>[\/et_pb_text][et_pb_text _builder_version=\"4.27.4\" _module_preset=\"default\" custom_css_free_form=\"img.inline-zoom {||  transition: transform 0.3s ease;||  display: inline-block;||  vertical-align: middle;||  max-width: 100%;||}||||img.inline-zoom:hover {||  transform: scale(2);||  z-index: 10;||}\" global_colors_info=\"{}\"]<p>Inspir\u00e9 par l\u2019\u00c9gypte ancienne et l\u2019art des cath\u00e9drales, G\u00e9rard d\u00e9couvre le bouddhisme au temple de Dashang Kagyu Ling en Bourgogne, o\u00f9 il rencontre Jamgon Kongtrul Rinpoch\u00e9 et Kalou Rinpoch\u00e9, et il se forme aupr\u00e8s de sculpteurs bhoutanais. La main de l\u2019artiste repr\u00e9sente-t-elle un pont entre l\u2019Orient et l\u2019Occident, l\u2019expression d\u2019une qu\u00eate spirituelle ?<\/p>\r\n<blockquote>\r\n<p>Moi qui ai commenc\u00e9 en Occident, sans r\u00e9f\u00e9rence, sans transmission, \u00e7a m\u2019a oblig\u00e9 \u00e0 interroger tout cela. Que transmet-on ? Tout n\u2019est pas codifi\u00e9. On est oblig\u00e9 de faire des choix. Pour moi, \u00e7a m\u2019a oblig\u00e9 \u00e0 essayer de revenir \u00e0 la source, \u00e0 l\u2019essentiel. Et d\u2019ailleurs les statues qu\u2019on fait ici, elles sont tr\u00e8s simples, sans beaucoup de d\u00e9tails.<\/p>\r\n<\/blockquote>\r\n<p>Contrairement \u00e0 celle de Kundreul Ling, l\u2019artiste a effectu\u00e9 <strong>l\u2019assemblage de la statue de l\u2019institut dans son atelier<\/strong>, en Bourgogne, pour la livrer en une seule pi\u00e8ce \u00e0 Dhagpo Kagyu Ling.<\/p>\r\n<p>Il aura fallu pr\u00e8s de quinze ans pour que les causes et conditions soient r\u00e9unies afin que le projet de l\u2019Institut puisse voir le jour. Le 15 ao\u00fbt 2002, la dalle de ce qui deviendra l\u2019institut est consacr\u00e9e par le Gyalwa Karmapa, ainsi que par le XIV<sup>e<\/sup> Shamarpa, et la premi\u00e8re pierre est pos\u00e9e. Le projet est interrompu en cours de route pour \u00eatre r\u00e9vis\u00e9 et mieux adapt\u00e9 au lieu et aux besoins. Il red\u00e9marre en 2010 et sera achev\u00e9 sans entrave. Inaugur\u00e9 et d\u00e9sormais consacr\u00e9, le b\u00e2timent de l\u2019Institut permet aujourd\u2019hui de partager l\u2019enseignement du Bouddha de mani\u00e8re authentique, de l\u2019apprendre ensemble et ainsi, de cheminer vers l\u2019\u00e9veil. La sagesse \u00e9manant de la statue du Bouddha dans l\u2019institut est une <strong>invitation \u00e0 la contemplation et une source de b\u00e9n\u00e9diction<\/strong> pour toutes les personnes qui se trouvent en sa pr\u00e9sence.<\/p>[\/et_pb_text][et_pb_text admin_label=\"nextgen \" _builder_version=\"4.27.4\" _module_preset=\"default\" background_color=\"#d4b16a\" custom_margin=\"0px||||false|false\" custom_padding=\"|0px||0px|false|false\" border_width_bottom=\"1px\" border_color_bottom=\"#ab0032\" locked=\"off\" global_colors_info=\"{}\"]<p>[ngg src=\"galleries\" ids=\"77\" display=\"pro_tile\" order_by=\"filename\"]<\/p>[\/et_pb_text][et_pb_text disabled_on=\"on|on|off\" _builder_version=\"4.27.4\" _module_preset=\"default\" text_font=\"Roboto||||||||\" text_font_size=\"13px\" text_line_height=\"1em\" custom_padding=\"||0px|||\" locked=\"off\" global_colors_info=\"{}\"]<p style=\"text-align: center;\"><span style=\"color: #808080;\">Ces photos proviennent de nos archives ou ont \u00e9t\u00e9 recueillies dans le cadre des recherches pour les 50 ans de Dhagpo Kagyu Ling. Nous n'avons pas pu identifier tous les auteurs. L\u2019utilisation des photos est \u00e0 titre informatif dans le cadre de la c\u00e9l\u00e9bration des 50 ans de Dhagpo Kagyu Ling. Leur usage est limit\u00e9 \u00e0 cette actualit\u00e9 et \u00e0 notre site et n\u2019est pas \u00e0 usage commercial<\/span><\/p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][et_pb_column type=\"1_4\" _builder_version=\"4.16\" custom_padding=\"|||\" global_colors_info=\"{}\" custom_padding__hover=\"|||\"][et_pb_text module_class=\"event50\" _builder_version=\"4.27.4\" _module_preset=\"default\" text_font=\"||||||||\" text_font_size=\"16px\" text_line_height=\"20px\" header_4_text_color=\"gcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138\" header_5_text_color=\"gcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138\" header_5_font_size=\"18px\" background_color=\"gcid-b7d546b1-e8dd-4bef-9120-39ab5cda29e6\" background_image=\"https:\/\/dhagpo.org\/wp-content\/uploads\/2024\/12\/50ans-1.png\" background_size=\"custom\" background_image_width=\"40px\" background_position=\"top_right\" background_horizontal_offset=\"9px\" background_vertical_offset=\"6px\" custom_margin=\"||||false|false\" custom_margin_tablet=\"30px|100px|||false|false\" custom_margin_phone=\"|0px||0px|false|false\" custom_margin_last_edited=\"off|desktop\" custom_padding=\"|20px|15px|20px|false|false\" custom_padding_tablet=\"|20px|15px|20px|false|false\" custom_padding_phone=\"||||false|false\" custom_padding_last_edited=\"on|desktop\" custom_css_main_element=\"font-weight:500;\" custom_css_free_form=\".event50 h5 {||  display: inline-block;||  background-color: #ffffff; \/* Fond blanc *\/||  box-shadow: 0 2px 4px rgba(0, 0, 0, 0.1); \/* Optionnel : l\u00e9g\u00e8re ombre *\/||  padding: 5px; \/* Ajuster selon vos besoins *\/||  margin-bottom:10px;||  text-align: left; \/* Garde le texte align\u00e9 \u00e0 gauche *\/||||}||\" locked=\"off\" global_colors_info=\"{%22gcid-b7d546b1-e8dd-4bef-9120-39ab5cda29e6%22:%91%22background_color%22,%22background_color%22,%22background_color%22,%22background_color%22%93,%22gcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138%22:%91%22header_4_text_color%22,%22header_5_text_color%22,%22header_4_text_color%22,%22header_5_text_color%22%93}\"]<h5>\u00c9v\u00e9nement<\/h5>\r\nPour comm\u00e9morer cet \u00e9v\u00e9nement, nous r\u00e9citerons des pri\u00e8res de souhaits des Kagyu Meunlams  de 11 h \u00e0 12 h 30 dans le Temple.[\/et_pb_text][et_pb_button button_url=\"https:\/\/dhagpo.org\/calendrier\/50-ans-arrivee-retraitants-dhagpo-kagyu-ling-consecration-institut\/\" button_text=\"Voir dans le calendrier du programme\" disabled_on=\"off|off|off\" _builder_version=\"4.27.4\" _module_preset=\"default\" button_text_color=\"gcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138\" button_bg_color=\"#FFFFFF\" button_border_color=\"gcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138\" button_border_radius=\"6px\" button_icon=\"\uf073||fa||400\" button_icon_placement=\"left\" locked=\"off\" global_colors_info=\"{%22gcid-4bb20c8d-5a19-4f4f-8a7e-cb9fb4184138%22:%91%22button_text_color%22,%22button_border_color%22,%22button_border_color__hover%22%93}\" button_bg_color__hover_enabled=\"on|desktop\" button_border_radius__hover=\"6px\" button_border_color__hover_enabled=\"on|hover\" button_border_color__hover=\"#b87d06\" button_bg_color__hover=\"#FFFFFF\"][\/et_pb_button][et_pb_text disabled_on=\"off|off|on\" _builder_version=\"4.27.4\" _module_preset=\"default\" text_font=\"Roboto||||||||\" text_font_size=\"13px\" text_line_height=\"1em\" custom_padding=\"||0px|||\" locked=\"off\" global_colors_info=\"{}\"]<p style=\"text-align: center;\"><span style=\"color: #808080;\">Ces photos proviennent de nos archives ou ont \u00e9t\u00e9 recueillies dans le cadre des recherches pour les 50 ans de Dhagpo Kagyu Ling. Nous n'avons pas pu identifier tous les auteurs. L\u2019utilisation des photos est \u00e0 titre informatif dans le cadre de la c\u00e9l\u00e9bration des 50 ans de Dhagpo Kagyu Ling. Leur usage est limit\u00e9 \u00e0 cette actualit\u00e9 et \u00e0 notre site et n\u2019est pas \u00e0 usage commercial<\/span><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_section]","_et_gb_content_width":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[27],"tags":[],"class_list":["post-322925","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar","et-doesnt-have-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling - Dhagpo Kagyu Ling<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling - Dhagpo Kagyu Ling\" \/>\n<meta property=\"og:description\" content=\"Dos a\u00f1os despu\u00e9s de su inauguraci\u00f3n por Kunzig Shamar Rimpoch\u00e9, el Instituto Dhagpo Kagyu Ling fue formalmente consagrado y la estatua del Buda Shakyamuni fue desvelada por Thaye Dorje, Su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/\" \/>\n<meta property=\"og:site_name\" content=\"Dhagpo Kagyu Ling\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-25T15:39:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T08:28:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dhagpo.org\/wp-content\/uploads\/2000\/06\/31_karmapa-dhagpo-institut-31.jpg\" \/>\n<meta name=\"author\" content=\"yone\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"yone\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/\"},\"author\":{\"name\":\"yone\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/#\\\/schema\\\/person\\\/5599c0ac81613f26c092fd8eb9b35828\"},\"headline\":\"31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling\",\"datePublished\":\"2025-06-25T15:39:31+00:00\",\"dateModified\":\"2025-06-26T08:28:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/\"},\"wordCount\":1631,\"image\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhagpo.org\\\/wp-content\\\/uploads\\\/2000\\\/06\\\/31_karmapa-dhagpo-institut-31.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/\",\"url\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/\",\"name\":\"31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling - Dhagpo Kagyu Ling\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dhagpo.org\\\/wp-content\\\/uploads\\\/2000\\\/06\\\/31_karmapa-dhagpo-institut-31.jpg\",\"datePublished\":\"2025-06-25T15:39:31+00:00\",\"dateModified\":\"2025-06-26T08:28:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/#\\\/schema\\\/person\\\/5599c0ac81613f26c092fd8eb9b35828\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dhagpo.org\\\/wp-content\\\/uploads\\\/2000\\\/06\\\/31_karmapa-dhagpo-institut-31.jpg\",\"contentUrl\":\"https:\\\/\\\/dhagpo.org\\\/wp-content\\\/uploads\\\/2000\\\/06\\\/31_karmapa-dhagpo-institut-31.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dhagpo.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non classifi\u00e9(e)\",\"item\":\"https:\\\/\\\/dhagpo.org\\\/categorie\\\/non-classifiee\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/#website\",\"url\":\"https:\\\/\\\/dhagpo.org\\\/\",\"name\":\"Dhagpo Kagyu Ling\",\"description\":\"Un lieu pour comprendre et vivre le bouddhisme\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dhagpo.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dhagpo.org\\\/#\\\/schema\\\/person\\\/5599c0ac81613f26c092fd8eb9b35828\",\"name\":\"yone\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g\",\"caption\":\"yone\"},\"url\":\"https:\\\/\\\/dhagpo.org\\\/es\\\/author\\\/yone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling - Dhagpo Kagyu Ling","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/","og_locale":"es_ES","og_type":"article","og_title":"31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling - Dhagpo Kagyu Ling","og_description":"Dos a\u00f1os despu\u00e9s de su inauguraci\u00f3n por Kunzig Shamar Rimpoch\u00e9, el Instituto Dhagpo Kagyu Ling fue formalmente consagrado y la estatua del Buda Shakyamuni fue desvelada por Thaye Dorje, Su [&hellip;]","og_url":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/","og_site_name":"Dhagpo Kagyu Ling","article_published_time":"2025-06-25T15:39:31+00:00","article_modified_time":"2025-06-26T08:28:43+00:00","og_image":[{"url":"https:\/\/dhagpo.org\/wp-content\/uploads\/2000\/06\/31_karmapa-dhagpo-institut-31.jpg","type":"","width":"","height":""}],"author":"yone","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"yone","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/#article","isPartOf":{"@id":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/"},"author":{"name":"yone","@id":"https:\/\/dhagpo.org\/#\/schema\/person\/5599c0ac81613f26c092fd8eb9b35828"},"headline":"31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling","datePublished":"2025-06-25T15:39:31+00:00","dateModified":"2025-06-26T08:28:43+00:00","mainEntityOfPage":{"@id":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/"},"wordCount":1631,"image":{"@id":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/#primaryimage"},"thumbnailUrl":"https:\/\/dhagpo.org\/wp-content\/uploads\/2000\/06\/31_karmapa-dhagpo-institut-31.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/","url":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/","name":"31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling - Dhagpo Kagyu Ling","isPartOf":{"@id":"https:\/\/dhagpo.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/#primaryimage"},"image":{"@id":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/#primaryimage"},"thumbnailUrl":"https:\/\/dhagpo.org\/wp-content\/uploads\/2000\/06\/31_karmapa-dhagpo-institut-31.jpg","datePublished":"2025-06-25T15:39:31+00:00","dateModified":"2025-06-26T08:28:43+00:00","author":{"@id":"https:\/\/dhagpo.org\/#\/schema\/person\/5599c0ac81613f26c092fd8eb9b35828"},"breadcrumb":{"@id":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/#primaryimage","url":"https:\/\/dhagpo.org\/wp-content\/uploads\/2000\/06\/31_karmapa-dhagpo-institut-31.jpg","contentUrl":"https:\/\/dhagpo.org\/wp-content\/uploads\/2000\/06\/31_karmapa-dhagpo-institut-31.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dhagpo.org\/31-juillet-2015-consecration-institut-dhagpo-kagyu-ling\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dhagpo.org\/es\/"},{"@type":"ListItem","position":2,"name":"Non classifi\u00e9(e)","item":"https:\/\/dhagpo.org\/categorie\/non-classifiee\/"},{"@type":"ListItem","position":3,"name":"31 de julio de 2015: consagraci\u00f3n del Instituto Dhagpo Kagyu Ling"}]},{"@type":"WebSite","@id":"https:\/\/dhagpo.org\/#website","url":"https:\/\/dhagpo.org\/","name":"Dhagpo Kagyu Ling","description":"Un lieu pour comprendre et vivre le bouddhisme","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dhagpo.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/dhagpo.org\/#\/schema\/person\/5599c0ac81613f26c092fd8eb9b35828","name":"yone","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2402f0f9017586164852f9c9592c4a7b0fc5867bd36e54b9b2d93bcf2eefb11?s=96&d=mm&r=g","caption":"yone"},"url":"https:\/\/dhagpo.org\/es\/author\/yone\/"}]}},"_links":{"self":[{"href":"https:\/\/dhagpo.org\/es\/wp-json\/wp\/v2\/posts\/322925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dhagpo.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dhagpo.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dhagpo.org\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/dhagpo.org\/es\/wp-json\/wp\/v2\/comments?post=322925"}],"version-history":[{"count":11,"href":"https:\/\/dhagpo.org\/es\/wp-json\/wp\/v2\/posts\/322925\/revisions"}],"predecessor-version":[{"id":323306,"href":"https:\/\/dhagpo.org\/es\/wp-json\/wp\/v2\/posts\/322925\/revisions\/323306"}],"wp:attachment":[{"href":"https:\/\/dhagpo.org\/es\/wp-json\/wp\/v2\/media?parent=322925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dhagpo.org\/es\/wp-json\/wp\/v2\/categories?post=322925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dhagpo.org\/es\/wp-json\/wp\/v2\/tags?post=322925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}